{"id":9342,"date":"2020-11-04T13:32:03","date_gmt":"2020-11-04T12:32:03","guid":{"rendered":"https:\/\/kunakes.jaimezubiaur.com\/?p=9342"},"modified":"2025-05-29T13:07:48","modified_gmt":"2025-05-29T11:07:48","slug":"detectores-calidad-aire-movilidad","status":"publish","type":"post","link":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/","title":{"rendered":"Detectores de calidad del aire y movilidad, \u00bfqu\u00e9 nos cuentan los sistemas de monitorizaci\u00f3n?"},"content":{"rendered":"<h3 style=\"text-align: justify;\">PUNTOS DESTACADOS<\/h3>\n<ul>\n<li style=\"text-align: justify;\">El transporte sostenible tiene una incidencia directa sobre la calidad del aire, mejor\u00e1ndola.<\/li>\n<li style=\"text-align: justify;\">El tr\u00e1fico de veh\u00edculos representa una de las principales fuentes de contaminaci\u00f3n del aire en las ciudades.<\/li>\n<li style=\"text-align: justify;\">La crisis sanitaria provocada por el coronavirus ha cambiado los patrones de movilidad de muchas personas.<\/li>\n<li style=\"text-align: justify;\">La monitorizaci\u00f3n de la calidad del aire se configura como un valor en alza para certificar el \u00e9xito de las medidas orientadas a promover un transporte menos contaminante.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Detectores de calidad del aire y movilidad guardan una estrecha relaci\u00f3n. Al fin y al cabo, <strong>cuando la ciudadan\u00eda apuesta por un transporte sostenible, los \u00edndices de calidad del aire tienden a mejorar<\/strong>. Cuando el uso del veh\u00edculo privado gana terreno sobre otras opciones, las condiciones ambientales se resienten. Y los sistemas de monitorizaci\u00f3n ambiental muestran con claridad esta evoluci\u00f3n. De ah\u00ed su utilidad.<\/p>\n<p style=\"text-align: justify;\">Pero la s\u00fabita llegada del coronavirus y el temor a los contagios ha tra\u00eddo consigo m\u00faltiples cambios. Entre ellos, un replanteamiento de la movilidad diaria de las personas.<\/p>\n<p style=\"text-align: justify;\">\u00bfDe qu\u00e9 forma se dejan sentir estos cambios en la calidad del aire de las ciudades? \u00bfC\u00f3mo lo est\u00e1n reflejando los detectores de calidad de aire y qu\u00e9 rol est\u00e1n llamados a desempe\u00f1ar en la nueva realidad?<\/p>\n<p>&nbsp;<\/p>\n<h2>El tr\u00e1fico y las medidas disuasorias, una raz\u00f3n de peso para monitorizar la calidad del aire<\/h2>\n<p style=\"text-align: justify;\">Es indudable que en las decisiones que se toman en torno a la movilidad personal entran en juego diversos factores. Algunos est\u00e1n relacionados con la comodidad o la econom\u00eda. Otros, con la disponibilidad de diferentes medios de transporte o el tiempo de desplazamiento que exige cada medio. Y s\u00ed, algunas personas tambi\u00e9n ponen en consideraci\u00f3n la protecci\u00f3n ambiental. No en vano, <strong>las emisiones procedentes del tr\u00e1fico son una de las principales fuentes de contaminaci\u00f3n de las zonas urbanas<\/strong>. As\u00ed lo atestiguan an\u00e1lisis tales como <a href=\"https:\/\/www.eea.europa.eu\/soer\/2020\" target=\"_blank\" rel=\"noopener noreferrer\">The European environment \u2014 state and outlook 2020<\/a>, publicado por la Agencia Europea de Medio Ambiente a finales de 2019.<\/p>\n<p style=\"text-align: justify;\">Las ciudades llevan tiempo tratando de poner freno a esta situaci\u00f3n. De ah\u00ed que cada vez sean m\u00e1s habituales <strong>medidas<\/strong> tales como la delimitaci\u00f3n de zonas de bajas emisiones (ZBE), la progresiva electrificaci\u00f3n del transporte p\u00fablico o el fomento en el uso de transportes como la bicicleta. Y es indudable que <strong>una de las mejores maneras de verificar el \u00e9xito<\/strong> de estas medidas recae en el establecimiento de un <strong>sistema de monitorizaci\u00f3n ambiental<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Por esta raz\u00f3n, <strong>detectores de emisiones<\/strong> como nuestro <a href=\"https:\/\/kunakair.com\/es\/monitor-calidad-aire\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kunak AIR Pro<\/a> son sumamente \u00fatiles. Su relaci\u00f3n calidad-precio, la facilidad de instalaci\u00f3n y puesta en funcionamiento y su capacidad para transmitir datos en tiempo real <strong>permiten obtener una imagen fiel de los niveles de contaminaci\u00f3n<\/strong> en las ciudades y del \u00e9xito de las medidas puestas en funcionamiento. Como ya hemos <a href=\"https:\/\/kunakair.com\/es\/necesidad-estandares-y-programas-certificacion\/\" target=\"_blank\" rel=\"noopener noreferrer\">argumentado<\/a> en diversas ocasiones, no sustituyen a las redes oficiales de monitorizaci\u00f3n de calidad del aire, sino que las ampl\u00edan y complementan. De este modo, se puede abarcar m\u00e1s superficie a un menor coste y con una precisi\u00f3n muy cercana a la que proporcionan los equipos de referencia. Asimismo, posibilitan obtener un an\u00e1lisis de la situaci\u00f3n con una mayor resoluci\u00f3n, lo que puede facilitar las decisiones acerca de d\u00f3nde es necesario situar una estaci\u00f3n de referencia.<\/p>\n<p style=\"text-align: justify;\">Y en este intento de mejora la calidad de vida en las ciudades est\u00e1bamos cuando el coronavirus irrumpi\u00f3 y puso patas arriba todos nuestros comportamientos.<\/p>\n<p>&nbsp;<\/p>\n<h2>Menos tr\u00e1fico, mejor calidad del aire<\/h2>\n<p style=\"text-align: justify;\">Una de las primeras cosas que dej\u00f3 patente la pandemia fue <strong>la estrecha relaci\u00f3n entre tr\u00e1fico y calidad del aire<\/strong>. As\u00ed y a medida que los pa\u00edses se confinaban y restring\u00edan la circulaci\u00f3n, los miles de detectores de calidad del aire dispersos por el mundo, tanto oficiales como complementarios, comenzaron a mostrar c\u00f3mo descend\u00eda la concentraci\u00f3n de los distintos agentes contaminantes, como ya comentamos en nuestro <a href=\"https:\/\/kunakes.jaimezubiaur.com\/blog\/detectores-emisiones-coronavirus-contaminacion\/\" target=\"_blank\" rel=\"noopener noreferrer\">blog<\/a>. Los sistemas de monitorizaci\u00f3n del aire que Kunak tiene instalados en los <a href=\"https:\/\/www.portsdebalears.com\/es\/calidad-del-aire\" target=\"_blank\" rel=\"noopener noreferrer\">puertos mar\u00edtimos de Baleares<\/a> tambi\u00e9n mostraron este cambio.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Air pollution plummets by more than 45% in major European cities\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/GiuFle3rARA?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El planeta se convirti\u00f3, por decirlo de alguna forma, en un laboratorio en tiempo real.<\/p>\n<p style=\"text-align: justify;\">Pero conforme la situaci\u00f3n recuperaba cierta normalidad, los pa\u00edses reabrieron sus fronteras. Los veh\u00edculos volvieron a ocupar las calles de las ciudades y <strong>los niveles de contaminaci\u00f3n volvieron a crecer<\/strong>. No obstante, esta vuelta al pasado ha incorporado al tablero de juego un poderoso condicionante que puede alterar el curso de la partida: el temor al contagio por coronavirus.<\/p>\n<p>&nbsp;<\/p>\n<h3>Cuando el miedo dicta la movilidad personal<\/h3>\n<p style=\"text-align: justify;\">Andenes masificados, vagones atestados, autobuses repletos\u2026 <strong>La sensaci\u00f3n de inseguridad que transmite el transporte p\u00fablico est\u00e1 provocando que muchos de sus usuarios habituales renieguen ahora de su utilizaci\u00f3n<\/strong>, tal y como pone de manifiesto este esquema publicado por <a href=\"https:\/\/www.mckinsey.com\/industries\/automotive-and-assembly\/our-insights\/five-covid-19-aftershocks-reshaping-mobilitys-future\" target=\"_blank\" rel=\"noopener noreferrer\">McKinsey &amp; Company<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-movilidad-coronavirus.jpg\" alt=\"Movilidad, una cuesti\u00f3n influenciada por el coronavirus que queda reflejado por los detectores de calidad del aire\" width=\"1024\" height=\"792\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En muchos casos se trata de un temor poco fundado, ya que las <a href=\"https:\/\/www.agenciasinc.es\/Reportajes\/Mascarilla-distancia-y-ventilacion-las-claves-para-un-transporte-publico-seguro?s=09\" target=\"_blank\" rel=\"noopener noreferrer\">evidencias<\/a> apuntan que <strong>la observaci\u00f3n estricta de las medidas higi\u00e9nicas y sanitarias disminuye el riesgo<\/strong>. Sin embargo, la percepci\u00f3n negativa se ha asentado en gran parte de la sociedad y va a ser complicado revertir esta visi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En las ciudades que est\u00e1n sabiendo responder al problema con imaginaci\u00f3n y voluntad, facilitar en todo lo posible el uso de la bicicleta y favorecer la peatonalizaci\u00f3n de los centros urbanos se ha convertido en el nuevo mantra. Un ejemplo claro, <a href=\"https:\/\/www.forbes.com\/sites\/carltonreid\/2020\/10\/20\/paris-mayor-anne-hidalgo-to-make-good-on-pledge-to-remove-half-of-citys-car-parking-spaces\/\" target=\"_blank\" rel=\"noopener noreferrer\">Par\u00eds<\/a>.<\/p>\n<p style=\"text-align: justify;\">Pero all\u00e1 donde no se est\u00e1n adoptando medidas alternativas con celeridad, el uso del veh\u00edculo privado, con un \u00fanico ocupante, gana adeptos. El resultado, la posibilidad de que ciudades como Madrid puedan ver aumentados sus niveles de contaminaci\u00f3n hasta un 27 %, tal y como advert\u00eda recientemente <a href=\"https:\/\/www.ecologistasenaccion.org\/153593\/la-contaminacion-atmosferica-en-las-ciudades-podria-aumentar-hasta-un-27-despues-de-decadas-de-disminucion\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ecologistas en Acci\u00f3n<\/a>.<\/p>\n<p style=\"text-align: justify;\">Y las consecuencias de este cambio de comportamiento en la movilidad no pueden ser m\u00e1s nefastas:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>M\u00e1s contaminaci\u00f3n atmosf\u00e9rica<\/strong> que repercute de forma directa sobre la salud de las personas y, seg\u00fan las crecientes pruebas, podr\u00eda agravar la sintomatolog\u00eda de la COVID-19. En torno a la transmisibilidad, no existe a\u00fan un consenso generalizado, aunque no se descarta y es una cuesti\u00f3n que est\u00e1 siendo objeto de an\u00e1lisis.<\/li>\n<li style=\"text-align: justify;\"><strong>Mayores niveles de ruido<\/strong>, un agente contaminante del que sabemos que altera mecanismos tan fundamentales como el sue\u00f1o.<\/li>\n<li style=\"text-align: justify;\"><strong>Incremento en las emisiones de CO<sub>2<\/sub><\/strong>, con lo que este problema implica para el calentamiento global.<\/li>\n<li style=\"text-align: justify;\"><strong>Reducci\u00f3n de la actividad f\u00edsica<\/strong>, que se traduce en un mayor sedentarismo y una mayor incidencia de las enfermedades asociadas a la falta de ejercicio.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Medidas urgentes para no echar por la borda a\u00f1os de mejoras<\/h2>\n<p style=\"text-align: justify;\">Las ciudades tienen ante s\u00ed el enorme reto de hacer que la ciudadan\u00eda se sienta segura frente a la pandemia y luchar al mismo tiempo contra la crisis clim\u00e1tica. Ambas cuestiones deben ocupar lugares prioritarios en las agendas de las zonas urbanas. \u00bfC\u00f3mo conseguirlo? Aqu\u00ed van algunas <strong>medidas<\/strong> que benefician ambos prop\u00f3sitos:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Fomento de los trayectos a pie y uso de la bicicleta<\/strong>, dos de las medidas que mejores resultados est\u00e1n ofreciendo. Su puesta en pr\u00e1ctica asegura el distanciamiento f\u00edsico, reduce el nivel de emisiones e <a href=\"https:\/\/twitter.com\/BrentToderian\/status\/1313333126047780865\" target=\"_blank\" rel=\"noopener noreferrer\">incrementa la actividad f\u00edsica<\/a>. En las ciudades donde se est\u00e1n implantando, la acogida est\u00e1 siendo muy buena.<\/li>\n<li style=\"text-align: justify;\"><strong>Refuerzo del transporte p\u00fablico<\/strong>, siendo imprescindible reducir las frecuencias de paso para evitar aglomeraciones y hacer que las personas se sientan m\u00e1s seguras.<\/li>\n<li style=\"text-align: justify;\"><strong>Monitorizaci\u00f3n en tiempo real de la inmisi\u00f3n y comunicaci\u00f3n p\u00fablica<\/strong>. Es fundamental hacer ver a la gente la relaci\u00f3n entre contaminaci\u00f3n y salud y tr\u00e1fico y emisiones. La calidad del aire debe convertirse en un factor de decisi\u00f3n en todo lo concerniente a la movilidad personal.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Conclusi\u00f3n<\/h2>\n<p style=\"text-align: justify;\">Hacer posible que las ciudades conozcan en todo momento c\u00f3mo es la calidad del aire es una de las mejores formas de reforzar la salud p\u00fablica y la concienciaci\u00f3n ambiental y social. Por eso en Kunak creemos que la monitorizaci\u00f3n de la calidad del aire debe convertirse en una herramienta m\u00e1s para luchar contra la pandemia y los nuevos h\u00e1bitos impulsados por el miedo que trata de implantar.<\/p>\n<p style=\"text-align: justify;\">Al fin y al cabo, la contaminaci\u00f3n del aire nunca ha sido un juego. Y, en estos momentos, a\u00fan menos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud. Descubre aqu\u00ed c\u00f3mo.<\/p>\n","protected":false},"author":6,"featured_media":22528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[164],"tags":[339,348,245],"resources":[379,393],"class_list":["post-9342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-calidad-del-aire-en-ciudades","tag-contaminacion-urbana","tag-control-de-la-contaminacion-atmosferica","resources-articulos","resources-contaminacion-urbana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detectores de calidad del aire y movilidad - Kunak<\/title>\n<meta name=\"description\" content=\"Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detectores de calidad del aire y movilidad - Kunak\" \/>\n<meta property=\"og:description\" content=\"Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KunakTechnologies\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/kunakair\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T12:32:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T11:07:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:site\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detectores de calidad del aire y movilidad - Kunak","description":"Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/","og_locale":"es_ES","og_type":"article","og_title":"Detectores de calidad del aire y movilidad - Kunak","og_description":"Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud.","og_url":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/","og_site_name":"Kunak","article_publisher":"https:\/\/www.facebook.com\/KunakTechnologies\/","article_author":"https:\/\/www.facebook.com\/kunakair","article_published_time":"2020-11-04T12:32:03+00:00","article_modified_time":"2025-05-29T11:07:48+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg","type":"image\/jpeg"}],"author":"Equipo de marketing y comunicaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@KunaK_sensing","twitter_site":"@KunaK_sensing","twitter_misc":{"Escrito por":"Equipo de marketing y comunicaci\u00f3n","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#article","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/"},"author":{"name":"Equipo de marketing y comunicaci\u00f3n","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23"},"headline":"Detectores de calidad del aire y movilidad, \u00bfqu\u00e9 nos cuentan los sistemas de monitorizaci\u00f3n?","datePublished":"2020-11-04T12:32:03+00:00","dateModified":"2025-05-29T11:07:48+00:00","mainEntityOfPage":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/"},"wordCount":1461,"publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"image":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg","keywords":["Calidad del aire en ciudades","Contaminaci\u00f3n urbana","Control de la contaminaci\u00f3n atmosf\u00e9rica"],"articleSection":["Art\u00edculos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/","url":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/","name":"Detectores de calidad del aire y movilidad - Kunak","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#primaryimage"},"image":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg","datePublished":"2020-11-04T12:32:03+00:00","dateModified":"2025-05-29T11:07:48+00:00","description":"Los detectores de calidad del aire pueden jugar un importante rol en todo lo relacionado con la movilidad y la afecci\u00f3n sobre la salud.","breadcrumb":{"@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#primaryimage","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/11\/detectores-de-calidad-del-aire-trafico-coronavirus.jpg","width":888,"height":500,"caption":"Detectores de calidad del aire, contaminaci\u00f3n y movilidad, una cuesti\u00f3n influenciada por el coronavirus."},{"@type":"BreadcrumbList","@id":"https:\/\/kunakair.com\/es\/detectores-calidad-aire-movilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kunakair.com\/es\/"},{"@type":"ListItem","position":2,"name":"Detectores de calidad del aire y movilidad, \u00bfqu\u00e9 nos cuentan los sistemas de monitorizaci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/kunakair.com\/es\/#website","url":"https:\/\/kunakair.com\/es\/","name":"KUNAK","description":"Sensing anywhere","publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"alternateName":"Sensing anywhere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunakair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kunakair.com\/es\/#organization","name":"KUNAK","alternateName":"Sensing anywhere","url":"https:\/\/kunakair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","width":1000,"height":1000,"caption":"KUNAK"},"image":{"@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KunakTechnologies\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.youtube.com\/channel\/UC-suigTybwCW50od_rhTZxg"]},{"@type":"Person","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23","name":"Equipo de marketing y comunicaci\u00f3n","sameAs":["https:\/\/www.facebook.com\/kunakair","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.youtube.com\/@kunakair"],"url":"https:\/\/kunakair.com\/es\/author\/kunak\/"}]}},"_links":{"self":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/9342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/comments?post=9342"}],"version-history":[{"count":4,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/9342\/revisions"}],"predecessor-version":[{"id":30688,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/9342\/revisions\/30688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media\/22528"}],"wp:attachment":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media?parent=9342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/categories?post=9342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/tags?post=9342"},{"taxonomy":"resources","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/resources?post=9342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}