{"id":6869,"date":"2020-04-27T08:41:00","date_gmt":"2020-04-27T07:41:00","guid":{"rendered":"https:\/\/kunakes.jaimezubiaur.com\/air-quality-monitoring-devices-performance-uses\/"},"modified":"2026-06-15T12:51:58","modified_gmt":"2026-06-15T10:51:58","slug":"sensores-calidad-aire-exterior-rendimiento-uso","status":"publish","type":"post","link":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/","title":{"rendered":"Rendimiento y uso de sensores de calidad del aire de bajo costo"},"content":{"rendered":"<section data-id=\"3def448\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">La <strong>Conferencia sobre la Calidad del Aire<\/strong> <strong>2020<\/strong> era uno de los eventos destacados por Kunak para este a\u00f1o. Nuestra intenci\u00f3n era presentar dos estudios:<\/p>\n<\/section>\n<section data-id=\"5d0b39e\" data-element_type=\"section\">\n<ul>\n<li>Un an\u00e1lisis del rendimiento que ofrecen los sensores de calidad del aire low cost.<\/li>\n<li>Un ejemplo pr\u00e1ctico de c\u00f3mo se mide la contaminaci\u00f3n del aire exterior con dispositivos de bajo coste en instalaciones deportivas.<\/li>\n<\/ul>\n<\/section>\n<section data-id=\"b314b3e\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">Pero la crisis sanitaria mundial causada por la propagaci\u00f3n del COVID-19 oblig\u00f3 a cancelar el evento. En su lugar, se decidi\u00f3 celebrar una <strong>conferencia en l\u00ednea<\/strong> cuyo programa se puede encontrar en la p\u00e1gina <a target=\"_blank\" href=\"https:\/\/airquality2020.meng.auth.gr\/programme\/\">web oficial<\/a>. Nuestras comunicaciones est\u00e1n incluidas en las secciones \u00ab<em>Sensors, Crowd Sourcing and Air Quality Model Simulations\u00bb y \u00abExposure and Health Assessment Related to Air Pollution<\/em>\u00bb respectivamente.<\/p>\n<p>&nbsp;<\/p>\n<\/section>\n<h2>Rendimiento de los dispositivos de vigilancia de la calidad del aire de bajo costo: conclusiones tras un a\u00f1o de pruebas<\/h2>\n<section data-id=\"2aea399\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">El objetivo de nuestro estudio \u00ab<em><b>Low Cost Sensor Behaviour Assessment: Dealing with Long-Term Drifts<\/b><\/em>\u00bb es mostrar el rendimiento que ofrecen los equipos de vigilancia del aire de bajo costo para medir la contaminaci\u00f3n del aire.<\/p>\n<\/section>\n<section data-id=\"06516c4\" data-element_type=\"section\">Este tipo de dispositivos, como comentamos en nuestro <a target=\"_blank\" href=\"https:\/\/kunakes.jaimezubiaur.com\/blog\/\">blog<\/a>, <strong>no son sustitutos de los equipos de referencia<\/strong>. Pero pueden ser apropiados para otras aplicaciones como:<\/section>\n<section data-id=\"ac0baef\" data-element_type=\"section\">\n<ul>\n<li style=\"text-align: justify;\">Estudios de investigaci\u00f3n, que prometen lograr la relevancia para verificar la asociaci\u00f3n COVID-19 y la contaminaci\u00f3n del aire sugerida por algunas publicaciones.<\/li>\n<li style=\"text-align: justify;\">Apoyo adicional a las redes de calidad del aire existentes.<\/li>\n<li style=\"text-align: justify;\">Identificaci\u00f3n y caracterizaci\u00f3n de las fuentes de contaminaci\u00f3n.<\/li>\n<\/ul>\n<\/section>\n<section data-id=\"6cd160b\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">Sin embargo, para obtener resultados \u00fatiles, es necesario utilizar <strong>sensores que proporcionen datos de alta calidad<\/strong>. Por lo tanto, con el fin de analizar el rendimiento de nuestro equipo, hemos llevado a cabo una evaluaci\u00f3n de un a\u00f1o de nuestro Kunak AIR. En el curso de este estudio, comparamos nuestro dispositivo con una estaci\u00f3n de referencia fija, una m\u00f3vil y otro Kunak Air-10, en 4 situaciones diferentes (ambiental, ubicaci\u00f3n, \u00e9poca del a\u00f1o, etc.).<\/p>\n<\/section>\n<section data-id=\"99b9741\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">Los resultados del an\u00e1lisis concluyen que el Kunak AIR ofrece una <strong>precisi\u00f3n y exactitud muy cercana a la que proporcionan las estaciones de referencia<\/strong>. Tambi\u00e9n encontramos que los problemas de estabilidad a largo plazo y las desviaciones que estos tipos de sensores suelen mostrar pueden ser resueltos controlando el dispositivo de forma remota.<\/p>\n<\/section>\n<div class=\"_3d-flip-book  fb3d-fullscreen-mode full-size\" data-id=\"0\" data-mode=\"fullscreen\" data-title=\"false\" data-template=\"short-white-book-view\" data-lightbox=\"dark-shadow\" data-urlparam=\"fb3d-page\" data-page-n=\"0\" data-pdf=\"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/abstractaq2020mexico-200421115428.pdf\" data-tax=\"null\" data-thumbnail=\"\" data-cols=\"3\" data-book-template=\"default\" data-trigger=\"\"><\/div>\n<p>&nbsp;<\/p>\n<h2>Uso de sensores de calidad del aire: un proyecto piloto en Yokohama, Jap\u00f3n<\/h2>\n<section data-id=\"a64dda3\" data-element_type=\"section\">\n<p style=\"text-align: justify;\">El objetivo principal del estudio <strong>\u00ab<em>Athletes Exposure to Air Pollution during World Athletics World Relays: a Pilot Study<\/em>\u00ab<\/strong> es mostrar c\u00f3mo se mide la calidad del aire en las instalaciones deportivas.<\/p>\n<p style=\"text-align: justify;\"><strong>La contaminaci\u00f3n del aire tiene un impacto negativo en el rendimiento deportivo de los atletas<\/strong>. Las razones por las que este grupo puede estar en mayor riesgo son:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Aumento de la ventilaci\u00f3n durante el ejercicio.<\/li>\n<li style=\"text-align: justify;\">Un mayor volumen de aire inhalado por la boca, que no tiene mecanismos de filtraci\u00f3n como la nariz.<\/li>\n<li style=\"text-align: justify;\">El aumento de la velocidad del flujo de aire. Esta caracter\u00edstica permite que los contaminantes lleguen a las \u00e1reas m\u00e1s profundas del tracto respiratorio.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Este estudio piloto en Yokohama llev\u00f3 a <strong>dos conclusiones importantes<\/strong>:<\/p>\n<ul>\n<li style=\"text-align: justify;\">La utilidad de la <strong>evaluaci\u00f3n por hora de la contaminaci\u00f3n<\/strong> del aire, que permite programar las competiciones y los entrenamientos en las horas con menor nivel de contaminaci\u00f3n; y,<\/li>\n<li style=\"text-align: justify;\">La <strong>conveniencia de seguir desarrollando estudios, incluso a nivel individual de cada atleta<\/strong>. De esta manera, ser\u00eda posible entender mejor c\u00f3mo la contaminaci\u00f3n del aire afecta al rendimiento deportivo.<\/li>\n<\/ul>\n<\/section>\n<div class=\"_3d-flip-book  fb3d-fullscreen-mode full-size\" data-id=\"0\" data-mode=\"fullscreen\" data-title=\"false\" data-template=\"short-white-book-view\" data-lightbox=\"dark-shadow\" data-urlparam=\"fb3d-page\" data-page-n=\"0\" data-pdf=\"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/Reche2020_Athletes-exposure-to-air-pollution-during-World-Athletics-Relays.pdf\" data-tax=\"null\" data-thumbnail=\"\" data-cols=\"3\" data-book-template=\"default\" data-trigger=\"\"><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste<\/p>\n","protected":false},"author":6,"featured_media":22118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[164],"tags":[360],"resources":[379,396],"class_list":["post-6869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-sensor-de-calidad-del-aire","resources-articulos","resources-productos-kunak"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sensores de calidad del aire, dos ejemplos de uso - Kunak<\/title>\n<meta name=\"description\" content=\"Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sensores de calidad del aire, dos ejemplos de uso - Kunak\" \/>\n<meta property=\"og:description\" content=\"Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KunakTechnologies\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/kunakair\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T07:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T10:51:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:site\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sensores de calidad del aire, dos ejemplos de uso - Kunak","description":"Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/","og_locale":"es_ES","og_type":"article","og_title":"Sensores de calidad del aire, dos ejemplos de uso - Kunak","og_description":"Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste","og_url":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/","og_site_name":"Kunak","article_publisher":"https:\/\/www.facebook.com\/KunakTechnologies\/","article_author":"https:\/\/www.facebook.com\/kunakair","article_published_time":"2020-04-27T07:41:00+00:00","article_modified_time":"2026-06-15T10:51:58+00:00","og_image":[{"width":900,"height":500,"url":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg","type":"image\/jpeg"}],"author":"Equipo de marketing y comunicaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@KunaK_sensing","twitter_site":"@KunaK_sensing","twitter_misc":{"Escrito por":"Equipo de marketing y comunicaci\u00f3n","Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#article","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/"},"author":{"name":"Equipo de marketing y comunicaci\u00f3n","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23"},"headline":"Rendimiento y uso de sensores de calidad del aire de bajo costo","datePublished":"2020-04-27T07:41:00+00:00","dateModified":"2026-06-15T10:51:58+00:00","mainEntityOfPage":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/"},"wordCount":634,"publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"image":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg","keywords":["Sensor de calidad del aire"],"articleSection":["Art\u00edculos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/","url":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/","name":"Sensores de calidad del aire, dos ejemplos de uso - Kunak","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#primaryimage"},"image":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg","datePublished":"2020-04-27T07:41:00+00:00","dateModified":"2026-06-15T10:51:58+00:00","description":"Resumen de los dos estudios presentados en la 12\u00aa Conferencia sobre la Calidad del Aire 2020 sobre sensores de calidad del aire de bajo coste","breadcrumb":{"@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#primaryimage","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2020\/04\/sensores-de-calidad-del-aire-usos-rendimiento.jpg","width":900,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/kunakair.com\/es\/sensores-calidad-aire-exterior-rendimiento-uso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kunakair.com\/es\/"},{"@type":"ListItem","position":2,"name":"Rendimiento y uso de sensores de calidad del aire de bajo costo"}]},{"@type":"WebSite","@id":"https:\/\/kunakair.com\/es\/#website","url":"https:\/\/kunakair.com\/es\/","name":"KUNAK","description":"Sensing anywhere","publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"alternateName":"Sensing anywhere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunakair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kunakair.com\/es\/#organization","name":"KUNAK","alternateName":"Sensing anywhere","url":"https:\/\/kunakair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","width":1000,"height":1000,"caption":"KUNAK"},"image":{"@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KunakTechnologies\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.youtube.com\/channel\/UC-suigTybwCW50od_rhTZxg"]},{"@type":"Person","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23","name":"Equipo de marketing y comunicaci\u00f3n","sameAs":["https:\/\/www.facebook.com\/kunakair","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.youtube.com\/@kunakair"],"url":"https:\/\/kunakair.com\/es\/author\/kunak\/"}]}},"_links":{"self":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/6869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/comments?post=6869"}],"version-history":[{"count":4,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/6869\/revisions"}],"predecessor-version":[{"id":63328,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/6869\/revisions\/63328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media\/22118"}],"wp:attachment":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media?parent=6869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/categories?post=6869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/tags?post=6869"},{"taxonomy":"resources","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/resources?post=6869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}