{"id":4886,"date":"2018-11-13T12:45:50","date_gmt":"2018-11-13T10:45:50","guid":{"rendered":"https:\/\/kunakes.jaimezubiaur.com\/kunak-selected-for-business-acceleration-event-with-suez-in-barcelona\/"},"modified":"2026-06-15T13:02:03","modified_gmt":"2026-06-15T11:02:03","slug":"kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona","status":"publish","type":"post","link":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/","title":{"rendered":"Kunak seleccionado para un evento de aceleraci\u00f3n de negocios con SUEZ en Barcelona"},"content":{"rendered":"<p>La tecnolog\u00eda juega un papel vital en ayudar a empresas y consumidores a realizar una transici\u00f3n hacia un mundo m\u00e1s fuerte en el que los recursos se utilicen de una manera m\u00e1s sostenible. El evento de SUEZ se centrar\u00e1 en enfoques innovadores para la gesti\u00f3n y distribuci\u00f3n del agua, la gesti\u00f3n de residuos, la calidad del aire, el an\u00e1lisis de datos, el IoT, la eficiencia energ\u00e9tica, la inspecci\u00f3n de activos y la gesti\u00f3n predictiva. Kunak presentar\u00e1 y participar\u00e1 en reuniones individuales con los directivos y socios de SUEZ.<\/p>\n<p>\u00abSUEZ est\u00e1 dise\u00f1ando soluciones innovadoras para desempe\u00f1ar un papel de liderazgo en la resoluci\u00f3n de los retos de sus clientes. Para contribuir a este objetivo, promueve la innovaci\u00f3n abierta con una serie de herramientas que tienen como objetivo desarrollar alianzas con las empresas tecnol\u00f3gicas m\u00e1s prometedoras. La colaboraci\u00f3n con el proyecto piloto EIC ayudar\u00e1 a reforzar la detecci\u00f3n de nuevas oportunidades para establecer colaboraciones exitosas. El evento contar\u00e1 con el apoyo de su socio local Aguas de Barcelona, que es un actor clave como lugar de demostraci\u00f3n de las nuevas soluciones y contribuye a la validaci\u00f3n de las nuevas tecnolog\u00edas a trav\u00e9s de su centro de investigaci\u00f3n de excelencia, Cetaqua\u00bb. Manuel Cermer\u00f3n, Director de Organizaci\u00f3n, Personas y Tecnolog\u00eda (SUEZ Espa\u00f1a).<\/p>\n<p>\u00abEstamos muy contentos de haber sido seleccionados para este evento promovido por el programa piloto de EIC. Creemos que nuestras soluciones innovadoras para la monitorizaci\u00f3n de la calidad del aire y el telecontrol para la gesti\u00f3n del agua est\u00e1n alineadas con el negocio de SUEZ y en este evento esperamos iniciar colaboraciones que nos ayuden a ampliar nuestro negocio. \u00bb\u00a0Javier Fern\u00e1ndez Huerta CEO y cofundador de Kunak Technologies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tecnolog\u00eda juega un papel vital en ayudar a empresas y consumidores a realizar una transici\u00f3n hacia un mundo m\u00e1s fuerte en el que los recursos se utilicen de una manera m\u00e1s sostenible. El evento de SUEZ se centrar\u00e1 en enfoques innovadores para la gesti\u00f3n y distribuci\u00f3n del agua, la gesti\u00f3n de residuos, la calidad [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[166],"tags":[359],"resources":[],"class_list":["post-4886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-monitorizacion-ambiental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kunak en el networking event de Suez en Barcelona | Kunak<\/title>\n<meta name=\"description\" content=\"Kunak compartir\u00e1 su visi\u00f3n sobre la econom\u00eda circular en el networking y pitching Event de SUEZ en el Museu Agbar de les Aig\u00fces de Barcelona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kunak en el networking event de Suez en Barcelona | Kunak\" \/>\n<meta property=\"og:description\" content=\"Kunak compartir\u00e1 su visi\u00f3n sobre la econom\u00eda circular en el networking y pitching Event de SUEZ en el Museu Agbar de les Aig\u00fces de Barcelona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KunakTechnologies\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/kunakair\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-13T10:45:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T11:02:03+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:site\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kunak en el networking event de Suez en Barcelona | Kunak","description":"Kunak compartir\u00e1 su visi\u00f3n sobre la econom\u00eda circular en el networking y pitching Event de SUEZ en el Museu Agbar de les Aig\u00fces de Barcelona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Kunak en el networking event de Suez en Barcelona | Kunak","og_description":"Kunak compartir\u00e1 su visi\u00f3n sobre la econom\u00eda circular en el networking y pitching Event de SUEZ en el Museu Agbar de les Aig\u00fces de Barcelona.","og_url":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/","og_site_name":"Kunak","article_publisher":"https:\/\/www.facebook.com\/KunakTechnologies\/","article_author":"https:\/\/www.facebook.com\/kunakair","article_published_time":"2018-11-13T10:45:50+00:00","article_modified_time":"2026-06-15T11:02:03+00:00","author":"Equipo de marketing y comunicaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@KunaK_sensing","twitter_site":"@KunaK_sensing","twitter_misc":{"Escrito por":"Equipo de marketing y comunicaci\u00f3n","Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#article","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/"},"author":{"name":"Equipo de marketing y comunicaci\u00f3n","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23"},"headline":"Kunak seleccionado para un evento de aceleraci\u00f3n de negocios con SUEZ en Barcelona","datePublished":"2018-11-13T10:45:50+00:00","dateModified":"2026-06-15T11:02:03+00:00","mainEntityOfPage":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"image":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#primaryimage"},"thumbnailUrl":"","keywords":["Monitorizaci\u00f3n ambiental"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/","url":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/","name":"Kunak en el networking event de Suez en Barcelona | Kunak","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-11-13T10:45:50+00:00","dateModified":"2026-06-15T11:02:03+00:00","description":"Kunak compartir\u00e1 su visi\u00f3n sobre la econom\u00eda circular en el networking y pitching Event de SUEZ en el Museu Agbar de les Aig\u00fces de Barcelona.","breadcrumb":{"@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/kunakair.com\/es\/kunak-seleccionado-para-un-evento-de-aceleracion-de-negocios-con-suez-en-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kunakair.com\/es\/"},{"@type":"ListItem","position":2,"name":"Kunak seleccionado para un evento de aceleraci\u00f3n de negocios con SUEZ en Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/kunakair.com\/es\/#website","url":"https:\/\/kunakair.com\/es\/","name":"KUNAK","description":"Sensing anywhere","publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"alternateName":"Sensing anywhere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunakair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kunakair.com\/es\/#organization","name":"KUNAK","alternateName":"Sensing anywhere","url":"https:\/\/kunakair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","width":1000,"height":1000,"caption":"KUNAK"},"image":{"@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KunakTechnologies\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.youtube.com\/channel\/UC-suigTybwCW50od_rhTZxg"]},{"@type":"Person","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23","name":"Equipo de marketing y comunicaci\u00f3n","sameAs":["https:\/\/www.facebook.com\/kunakair","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.youtube.com\/@kunakair"],"url":"https:\/\/kunakair.com\/es\/author\/kunak\/"}]}},"_links":{"self":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/4886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/comments?post=4886"}],"version-history":[{"count":1,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/4886\/revisions"}],"predecessor-version":[{"id":20554,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/4886\/revisions\/20554"}],"wp:attachment":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media?parent=4886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/categories?post=4886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/tags?post=4886"},{"taxonomy":"resources","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/resources?post=4886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}