{"id":15909,"date":"2022-01-18T09:02:45","date_gmt":"2022-01-18T08:02:45","guid":{"rendered":"https:\/\/kunakes.jaimezubiaur.com\/?p=15909"},"modified":"2026-06-15T12:45:50","modified_gmt":"2026-06-15T10:45:50","slug":"software-de-calidad-del-aire","status":"publish","type":"post","link":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/","title":{"rendered":"Kunak AIR Cloud, software de calidad del aire para el an\u00e1lisis y visualizaci\u00f3n de datos"},"content":{"rendered":"<h2>Kunak AIR Cloud, la plataforma web de gesti\u00f3n de la calidad del aire<\/h2>\r\n<p>Kunak AIR Cloud es un software de medici\u00f3n de calidad del aire que permite de forma sencilla el an\u00e1lisis de datos ambientales, donde es posible acceder en tiempo real a los datos recogidos por la red de sensores para tomar decisiones que ayuden a mejorar la calidad del aire del entorno y proteger la salud de las personas.<\/p>\r\n<p>La plataforma web Kunak AIR Cloud ofrece a los profesionales una nueva forma de operar la red, gestionar los dispositivos, configurar alarmas, calibrar y realizar operaciones de campo de forma remota, as\u00ed como de disponer una completa suite de herramientas para el an\u00e1lisis de los datos de calidad del aire.<\/p>\r\n<p>El software web Kunak AIR Cloud, en combinaci\u00f3n con las estaciones de monitorizaci\u00f3n ambiental Kunak Air Pro y Kunak AIR Lite, representa una sinergia perfecta en el \u00e1mbito de la gesti\u00f3n de la calidad del aire. Esta uni\u00f3n no solo suma las capacidades individuales de cada componente, sino que las potencia, logrando resultados que superan ampliamente las expectativas. En t\u00e9rminos simples, es como decir que uno m\u00e1s uno es mayor que dos.<\/p>\r\n<p>Se posiciona como una de las herramientas m\u00e1s avanzadas y poderosas disponibles en el mercado para el procesamiento de datos ambientales. Esta combinaci\u00f3n permite a los usuarios explotar los datos sobre contaminaci\u00f3n del aire de manera r\u00e1pida y sencilla, apoyando la toma de decisiones informadas y facilitando la gesti\u00f3n, mantenimiento y calibraci\u00f3n de las redes de sensores de calidad del aire.<\/p>\r\n<p>&nbsp;<\/p>\r\n\r\n<figure class=\"wp-block-image size-full\" style=\"text-align: center;\"><img decoding=\"async\" class=\"wp-image-15930\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/arquitectura-kunak-cloud.png\" alt=\"\" \/>\r\n<figcaption><em>Arquitectura de datos<\/em><\/figcaption>\r\n<\/figure>\r\n\r\n<h2>Caracter\u00edsticas y beneficios de Kunak AIR Cloud<\/h2>\r\n<p>Kunak AIR Cloud es una plataforma web profesional <strong>dise\u00f1ada para la gesti\u00f3n remota de redes de calidad del aire<\/strong>. Esta herramienta avanzada permite a los usuarios maximizar el potencial de los datos obtenidos por los <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/soluciones\/\">sistemas de monitorizaci\u00f3n Kunak AIR<\/a> y de otras fuentes externas. Al integrar y analizar estos datos, Kunak AIR Cloud proporciona una soluci\u00f3n integral que facilita el an\u00e1lisis y la gesti\u00f3n de datos ambientales de manera eficiente y precisa.<\/p>\r\n<p>Su interfaz intuitiva y f\u00e1cil de usar, permite a los usuarios acceder a informaci\u00f3n detallada y en tiempo real sobre la calidad del aire en diferentes ubicaciones y es especialmente \u00fatil para empresas u organizaciones que necesitan monitorear m\u00faltiples sitios simult\u00e1neamente. Adem\u00e1s, Kunak Air Cloud permite la personalizaci\u00f3n de los informes y visualizaciones de datos, adapt\u00e1ndose a las necesidades espec\u00edficas de cada usuario o proyecto.<\/p>\r\n<h3>Modelo SaaS: flexibilidad y eficiencia<\/h3>\r\n<p>El funcionamiento de Kunak AIR Cloud se basa en el modelo <strong>\u201csoftware como servicio\u201d o SaaS<\/strong> (por sus siglas en ingl\u00e9s <em>\u201dSoftware as a Service\u00bb<\/em>). Este enfoque, que se encuentra en la nube, ofrece al usuario todas las herramientas necesarias para extraer el m\u00e1ximo rendimiento de los datos recopilados por la red de sensores. Adem\u00e1s, al estar basado en la nube, Kunak AIR Cloud permite la gesti\u00f3n remota de dispositivos o redes de dispositivos, lo que facilita un control eficiente y centralizado desde cualquier lugar con acceso a Internet.<\/p>\r\n<p>Una de las principales ventajas de Kunak AIR Cloud es su flexibilidad. El software se puede contratar por <strong>m\u00f3dulos<\/strong>, lo que significa que los usuarios pueden seleccionar y pagar solo por las funcionalidades que realmente necesitan. De este modo el usuario puede adaptar el software a las necesidades espec\u00edficas de cada proyecto de monitorizaci\u00f3n de calidad del aire, optimizando as\u00ed los recursos y costes. Adem\u00e1s, este modelo garantiza que el software est\u00e9 siempre actualizado con las \u00faltimas mejoras y funcionalidades, sin necesidad de instalaciones adicionales por parte del usuario.<\/p>\r\n<h3>\u00bfPor qu\u00e9 Kunak AIR Cloud sobresale con respecto a otras opciones?<\/h3>\r\n<p>El mercado ofrece m\u00faltiples herramientas para visualizar y analizar datos relacionados con la calidad del aire. Pero <strong>pocas soluciones alcanzan el nivel de rendimiento y funcionalidades de Kunak AIR Cloud<\/strong>. Confiando en esta soluci\u00f3n, te vas a beneficiar de:<\/p>\r\n<ul>\r\n<li>La fiabilidad y seguridad en el manejo de datos.<\/li>\r\n<li>Orientaci\u00f3n al servicio, priorizando dar respuesta a las necesidades del cliente y haciendo posible utilidades tales como la creaci\u00f3n de perfiles de usuarios con distintos niveles de acceso.<\/li>\r\n<li>Las posibilidades que brinda para complementar y facilitar la toma de decisiones.<\/li>\r\n<li>Su facilidad de instalaci\u00f3n y manejo, respondiendo a la perfecci\u00f3n en distintos dispositivos (ordenador, <em>smartphone<\/em>, etc.).<\/li>\r\n<li>Gracias a su API, las opciones para compartir los datos o la integraci\u00f3n de los datos en otras aplicaciones, as\u00ed como la posibilidad de incorporar datos de fuentes externas para su an\u00e1lisis en conjunto.<\/li>\r\n<li>Su escalabilidad, adapt\u00e1ndose al crecimiento de tu red de estaciones basadas en sensores (de Kunak o estaciones de referencia).<\/li>\r\n<li>El excelente soporte t\u00e9cnico que proporciona Kunak.<\/li>\r\n<li>Las mejoras continuas con las que perfeccionamos el servicio, sin costes adicionales.<\/li>\r\n<\/ul>\r\n<p>Adem\u00e1s, cuando la monitorizaci\u00f3n de la calidad del aire de forma continua y en tiempo real recae sobre una red de estaciones Kunak AIR, Kunak AIR Cloud es la llave para:<\/p>\r\n<ul>\r\n<li>Configurar la red de equipos desplegados sobre el terreno.<\/li>\r\n<li>Monitorizar el estado de los equipos y detectar posibles anomal\u00edas.<\/li>\r\n<li>Establecer alarmas y avisos.<\/li>\r\n<li>Calibrar los sensores.<\/li>\r\n<li>Validar e invalidar datos.<\/li>\r\n<li>Registrar todas las tareas de mantenimiento y configuraci\u00f3n de la red.<\/li>\r\n<li>Y mucho m\u00e1s.<\/li>\r\n<\/ul>\r\n\r\n<div style=\"text-align: center;\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/XZTQYQF-bT0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\r\n<!-- \/wp:post-content -->\r\n<h3><span style=\"font-weight: 400;\">Paquetes disponibles seg\u00fan las necesidades de cada cliente<\/span><\/h3>\r\n<p><span style=\"font-weight: 400;\">Paquetizar es una opci\u00f3n por la que suelen optar muchas empresas. B\u00e1sicamente, consiste en facilitar al cliente las opciones de compra reduciendo y clasificando la oferta en torno a \u201cpaquetes\u201d de servicios. No en vano, est\u00e1 demostrado que una oferta excesiva puede generar indecisi\u00f3n.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">En Kunak siempre buscamos la m\u00e1xima satisfacci\u00f3n del cliente y conocemos cu\u00e1les son las principales demandas del mercado. As\u00ed pues, consideramos que paquetizar los servicios que ofrecemos a trav\u00e9s de Kunak AIR Cloud puede ser una gran forma de brindarte productos y servicios de alto valor a\u00f1adido que mejor se adapten a tus necesidades.<\/span><\/p>\r\n<p>Su configuraci\u00f3n es flexible, por lo que es posible adaptar el servicio con los m\u00f3dulos disponibles. As\u00ed el cliente puede seleccionar el paquete que mejor se adapte a las necesidades del proyecto y le permita sacar el m\u00e1ximo partido a los datos proporcionados por la red de sensores. El cliente puede elegir entre entre los siguientes paquetes:<\/p>\r\n<ul>\r\n<li><strong>Inicial<\/strong><\/li>\r\n<li><strong>Inicial + Operaci\u00f3n<\/strong><\/li>\r\n<li><strong>Inicial + An\u00e1lisis<\/strong><\/li>\r\n<li><strong>Completo<\/strong><\/li>\r\n<\/ul>\r\n<p>A continuaci\u00f3n detallamos las caracter\u00edsticas incluidas en cada uno de los paquetes:<\/p>\r\n<p><iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/spreadsheets\/d\/e\/2PACX-1vSASfj5Hw4it0b6PH6pgZtWR_KNe1BbVJi3RyObIXWogFPQ4Yki-s9C0x0HvVx0z5dAdIyRU89XiS4I\/pubhtml?gid=656178113&amp;single=true&amp;widget=true&amp;headers=false\" width=\"100%\" height=\"1000\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\r\n<h3><span style=\"font-weight: 400;\">Principales funcionalidades<\/span><\/h3>\r\n<p><span style=\"font-weight: 400;\">Aqu\u00ed te dejamos una muestra de las principales herramientas disponibles en la plataforma. No obstante, incluye muchas m\u00e1s que te facilitar\u00e1n tu operativa diaria.<\/span><\/p>\r\n\t\t\t\n\t\t<section class=\"knk-gallery\">\n\t\t\n\t\t\t<div class=\"swiper casegalerySwiper \">\n\t\t    \t\n\t\t    \t<div class=\"swiper-wrapper\">\n\n\t\t\t\t\t<a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-leakage-detection.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Detecci\u00f3n de posibles fugas\" data-title=\"Detecci\u00f3n de posibles fugas\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-leakage-detection-600x600.jpg\" class=\"img-responsive\" alt=\"Detecci\u00f3n de posibles fugas\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-control-paneljpg.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Panel de control\" data-title=\"Panel de control\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-control-paneljpg-600x600.jpg\" class=\"img-responsive\" alt=\"Panel de control\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-aqi.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Visualizaci\u00f3n del ICA\" data-title=\"Visualizaci\u00f3n del ICA\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-aqi-600x600.jpg\" class=\"img-responsive\" alt=\"Visualizaci\u00f3n del ICA\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-alarms.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Registro de alarmas y su trazabilidad\" data-title=\"Registro de alarmas y su trazabilidad\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-alarms-600x600.jpg\" class=\"img-responsive\" alt=\"Alertas y alarmas\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-cmms.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Registro de las tareas de mantenimiento en sus dispositivos (GMAO)\" data-title=\"Registro de las tareas de mantenimiento en sus dispositivos (GMAO)\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-cmms-600x600.jpg\" class=\"img-responsive\" alt=\"Registro de las tareas de mantenimiento en sus dispositivos (GMAO)\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-reports.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Validaci\u00f3n de datos y creaci\u00f3n de informes personalizados\" data-title=\"Validaci\u00f3n de datos y creaci\u00f3n de informes personalizados\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-reports-600x600.jpg\" class=\"img-responsive\" alt=\"Validaci\u00f3n de datos y creaci\u00f3n de informes personalizados\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pollution-rose.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Caracterizaci\u00f3n de las fuentes de contaminaci\u00f3n\" data-title=\"Caracterizaci\u00f3n de las fuentes de contaminaci\u00f3n\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pollution-rose-600x600.jpg\" class=\"img-responsive\" alt=\"Caracterizaci\u00f3n de las fuentes de contaminaci\u00f3n\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pollution-source.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Identificaci\u00f3n de las fuentes de contaminaci\u00f3n\" data-title=\"Identificaci\u00f3n de las fuentes de contaminaci\u00f3n\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pollution-source-600x600.jpg\" class=\"img-responsive\" alt=\"Identificaci\u00f3n de las fuentes de contaminaci\u00f3n\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pm-size.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"An\u00e1lisis del tama\u00f1o de las part\u00edculas y su distribuci\u00f3n\" data-title=\"An\u00e1lisis del tama\u00f1o de las part\u00edculas y su distribuci\u00f3n\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-pm-size-600x600.jpg\" class=\"img-responsive\" alt=\"An\u00e1lisis del tama\u00f1o de las part\u00edculas y su distribuci\u00f3n\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-analysis.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"An\u00e1lisis multiparam\u00e9tricos\" data-title=\"An\u00e1lisis multiparam\u00e9tricos\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-analysis-600x600.jpg\" class=\"img-responsive\" alt=\"An\u00e1lisis multiparam\u00e9tricos\" \/><\/a><a href=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-heatmap.jpg\" class=\"swiper-slide\" data-lightbox=\"roadtrip\" title=\"Identificaci\u00f3n de los puntos conflictivos\" data-title=\"Identificaci\u00f3n de los puntos conflictivos\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2024\/09\/pantalla-cloud-heatmap-600x600.jpg\" class=\"img-responsive\" alt=\"Identificaci\u00f3n de los puntos conflictivos\" \/><\/a>  \n\t\t\t    \n\t\t\t    <\/div>\n\t\t\t\n\t\t\t<\/div>\n\n\t\t\t<div class=\"slider-botones\">\n\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<\/div>\n\n\t\t<\/section>\n\n\t\t<script type=\"text\/javascript\" src=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@8\/swiper-bundle.min.js\" id=\"swiper-js\"><\/script>\n\n\t\r\n<h2>Novedades de nuestra plataforma cloud<\/h2>\r\n<p>Como coment\u00e1bamos anteriormente, nuestra plataforma web est\u00e1 siempre actualizada. As\u00ed, garantizamos que los clientes disfruten de cualquier nueva herramienta o funcionalidad de forma inmediata sin coste adicional.\u00a0Y las actualizaciones son constantes. En estos momentos, la versi\u00f3n 2.3.0 incluye algunas mejoras tan importantes como:<\/p>\r\n<ul>\r\n<li>Lanzamiento de la <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.kunak.kunak\" target=\"_blank\" rel=\"noopener\">nueva app para Android<\/a>.<\/li>\r\n<li>Nueva interfaz y mejoras en las capas de visualizaci\u00f3n avanzadas (mapas de calor, rosas de contaminaci\u00f3n, distribuci\u00f3n de part\u00edculas, etc.).<\/li>\r\n<li>Nueva secci\u00f3n para actualizar el firmware de los dispositivos.<\/li>\r\n<li>Creaci\u00f3n de widgets y p\u00e1ginas web personalizadas para compartir p\u00fablicamente.<\/li>\r\n<li>Posibilidad de consultar un hist\u00f3rico de ubicaciones de los dispositivos.<\/li>\r\n<li>Generaci\u00f3n de informes en espa\u00f1ol.<\/li>\r\n<li>Funcionalidad de a\u00f1adir l\u00edneas a los gr\u00e1ficos en la secci\u00f3n de datos est\u00e1ndar.<\/li>\r\n<li>Mejoras en la creaci\u00f3n de cuentas.<\/li>\r\n<li>Gesti\u00f3n de datos por ubicaciones asignando los dispositivos a ubicaciones espec\u00edficas.<\/li>\r\n<li>Notificaciones v\u00eda correo electr\u00f3nico.<\/li>\r\n<li>Sugerencias de mantenimiento y de ayuda a resoluci\u00f3n de problemas.<\/li>\r\n<li>Registro visual que permite ver d\u00f3nde, cu\u00e1ndo y c\u00f3mo se ha instalado el dispositivo.<\/li>\r\n<li>Estad\u00edsticas y gr\u00e1ficas avanzadas adicionales.<\/li>\r\n<li>Se han a\u00f1adido los idiomas portugu\u00e9s y franc\u00e9s.<\/li>\r\n<li>Descarga de certificados de cartucho.<\/li>\r\n<li>Posibilidad de descargar el certificado de cada cartucho.<\/li>\r\n<\/ul>\r\n<h2>Sectores donde usar nuestro software Kunak AIR Cloud<\/h2>\r\n<p>Anteriormente hemos descrito algunas de las funcionalidades clave del software de calidad del aire Kunak AIR Cloud as\u00ed como algunas de las mejoras que hemos ido implementando.\u00a0No obstante, es preciso indicar tambi\u00e9n aquellas algunas de las actividades que pueden beneficiarse de la herramienta para supervisar sus instalaciones o \u00e1reas de influencia para la medici\u00f3n de calidad del aire:<\/p>\r\n<h3>Urbano<\/h3>\r\n<p>La soluci\u00f3n integral formada por las <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/monitor-calidad-aire\/\">estaciones Kunak AIR<\/a> y la <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/software-de-medicion-calidad-del-aire\/\">plataforma Kunak AIR Cloud<\/a> constituye el complemento perfecto de las redes de estaciones de referencia que encontramos en las ciudades. Esta combinaci\u00f3n ampl\u00eda la cobertura y la precisi\u00f3n de las mediciones, ayudando a <strong>identificar puntos conflictivos de contaminaci\u00f3n atmosf\u00e9rica y ruido<\/strong> e incrementando la disponibilidad de datos.<\/p>\r\n<p>Se trata de una herramienta fundamental para las urbes que desean <strong>mejorar la calidad de vida<\/strong> de la ciudadan\u00eda a trav\u00e9s de tecnolog\u00edas innovadoras. As\u00ed, por ejemplo, se recomienda su uso en el control de las <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/zonas-de-bajas-emisiones-y-el-control-de-la-contaminacion-del-aire\/\">zonas de bajas emisiones (ZBE)<\/a> que cada vez m\u00e1s ciudades est\u00e1n implementando. La medici\u00f3n de calidad del aire es tambi\u00e9n una necesidad (y seg\u00fan la ciudad, una obligaci\u00f3n regulada) en los trabajos de demolici\u00f3n y obras, como apunt\u00e1bamos en el proyecto de la <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/contaminacion-del-aire-por-obras\/\">demolici\u00f3n del antiguo estadio de f\u00fatbol del Santiago Calder\u00f3n<\/a>.<\/p>\r\n<h3>Industrias<\/h3>\r\n<p>El t\u00e1ndem hardware y software de Kunak posibilita la <strong>monitorizaci\u00f3n de per\u00edmetros industriales<\/strong> para detectar emisiones fugitivas o, como en el caso de las estaciones de depuraci\u00f3n de aguas residuales, controlar la liberaci\u00f3n de compuestos que generan <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/monitorizacion-mal-olor-industrial\/\">contaminaci\u00f3n por malos olores<\/a>. En el caso de los puertos mar\u00edtimos y dentro de iniciativas que tratan de potenciar la sostenibilidad de estas infraestructuras (proyectos de Puertos Verdes o Green Ports), la monitorizaci\u00f3n de los niveles de contaminaci\u00f3n tambi\u00e9n ha adquirido gran relevancia en aras de reducir el impacto ambiental de las operaciones portuarias y preservar el bienestar del personal trabajador del puerto y los habitantes de la zona.<\/p>\r\n<h3>Puertos y Aeropuertos<\/h3>\r\n<p>La monitorizaci\u00f3n ambiental es una herramienta indispensable para el control de la contaminaci\u00f3n en el transporte mar\u00edtimo y a\u00e9reo. Estos sistemas permiten medir en tiempo real las emisiones de los barcos y aviones con una precisi\u00f3n excepcional, lo que facilita la identificaci\u00f3n de las principales fuentes contaminantes para poder <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/emisiones-atmosfericas\/\">controlar las emisiones atmosf\u00e9ricas<\/a>. Algunos proyectos donde nos encontramos son el <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/casos-de-exito\/monitorizacion-ambiental-mediante-boyas-en-neom\/\">puerto de Neom en Arabia Saudita<\/a>, los <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/casos-de-exito\/control-de-la-calidad-del-aire-en-puertos-apb\/\">puertos de las Islas Baleares en Espa\u00f1a<\/a> o el <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/case-studies\/monitoreo-ambiental-en-el-puerto-de-cotonu\/\">puerto de Coton\u00fa en Ben\u00edn<\/a>. Con los datos que proporcionan las redes de sensores, es posible dise\u00f1ar e implementar estrategias m\u00e1s efectivas para mitigar el impacto ambiental de las actividades portuarias impulsando la innovaci\u00f3n y la sostenibilidad en los puertos.<\/p>\r\n<h3>Construcci\u00f3n<\/h3>\r\n<p>Gracias a la informaci\u00f3n ofrecida por nuestras soluciones de medici\u00f3n de la calidad del aire, el avanzado sistema Kunak AIR Cloud permite acceder a mediciones precisas de las emisiones de polvo y gases contaminantes de las obras, los cuales proporcionan informaci\u00f3n fiable con la cual las empresas constructoras pueden identificar y controlar la contaminaci\u00f3n que est\u00e1n generando. Nuestra tecnolog\u00eda permite validar aquellas acciones que reduzcan su huella ambiental mientras protegen la salud del p\u00fablico y cumplen con las regulaciones ambientales.<\/p>\r\n<h3>Miner\u00eda<\/h3>\r\n<p>La miner\u00eda es una industria que puede generar altos niveles de <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/sectores\/contaminacion-del-aire-por-la-mineria\/\">contaminaci\u00f3n del aire<\/a> debido a sus procesos de extracci\u00f3n y transporte. El software de Kunak AIR Cloud es una herramienta esencial en este sector ya que permite la <strong>monitorizaci\u00f3n en tiempo real de la calidad del aire<\/strong>, proporcionando datos precisos y fiables que ayudan a las empresas mineras a <strong>cumplir con las normativas ambientales y a proteger la salud de sus trabajadores<\/strong>. Gracias a su capacidad de supervisi\u00f3n remota y la generaci\u00f3n de informes detallados, muchas empresas han podido reducir sus costes de producci\u00f3n gracias a la detecci\u00f3n de anomal\u00edas, sus tareas de mantenimiento y mejorar su cumplimiento regulatorio.<\/p>\r\n<h3>Investigaci\u00f3n y consultor\u00eda<\/h3>\r\n<p>Nuestro software facilita el <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/sectores\/estudio-de-la-contaminacion-atmosferica\/\">an\u00e1lisis de datos de calidad del aire<\/a>, permitiendo a los investigadores obtener insights accionables para sus estudios. Esto no solo mejora la precisi\u00f3n de los estudios, sino que tambi\u00e9n aumenta la confianza de los clientes en los resultados obtenidos.<\/p>\r\n<p>Adem\u00e1s, las consultoras ambientales pueden <strong>ofrecer a sus clientes soluciones basadas en datos precisos y actualizados<\/strong>. En proyectos de evaluaci\u00f3n del impacto ambiental, este software ha permitido a los consultores realizar an\u00e1lisis exhaustivos y presentar informes que cumplen con los m\u00e1s altos est\u00e1ndares de calidad.<\/p>\r\n<h2>\u00bfPor qu\u00e9 necesito una plataforma como Kunak AIR Cloud?<\/h2>\r\n<p>Si has le\u00eddo atentamente el art\u00edculo hasta este punto es f\u00e1cil que hayas llegado a la siguiente conclusi\u00f3n: <strong>es importante disponer de datos de calidad, pero \u00bfde qu\u00e9 sirve si no se dispone de las herramientas necesarias para analizarlos y tomar decisiones en base a ellos?<\/strong><\/p>\r\n<p>Las redes de sensores inal\u00e1mbricos tienen la capacidad de generar un gran volumen de datos que crece con el tiempo (1). Y esta informaci\u00f3n influye en la toma de decisiones tales como:<\/p>\r\n<ul>\r\n<li><em>\u00bfActivo el protocolo de nivel de contaminaci\u00f3n elevado? <\/em><\/li>\r\n<li><em>\u00bfDebo reforzar la atenci\u00f3n primaria ante un posible incremento en el n\u00famero de consultas m\u00e9dicas por ese incendio forestal que est\u00e1 a 20 km de la ciudad? <\/em><\/li>\r\n<li><em>\u00bfQu\u00e9 impacto podr\u00edan tener estos agentes contaminantes sobre el patrimonio arquitect\u00f3nico? <\/em><\/li>\r\n<\/ul>\r\n<p>La respuesta a estas cuestiones depende tambi\u00e9n de la informaci\u00f3n que se pone sobre la mesa. Es obvio que la calidad del instrumental de monitorizaci\u00f3n, su localizaci\u00f3n o la densidad de aparatos condiciona el an\u00e1lisis. En este sentido, nuestras estaciones Kunak AIR ofrecen una excelente fiabilidad. Pero no es menos cierto que <strong>disponer de las herramientas adecuadas permite \u201cdigerir\u201d esos datos brutos y extraer de ellos todo su potencial<\/strong>, a\u00f1adiendo funcionalidades tales como la configuraci\u00f3n de alertas o la validaci\u00f3n de datos.<\/p>\r\n<p>Kunak AIR Cloud no solo proporciona una plataforma robusta para el almacenamiento, <strong>visualizaci\u00f3n y an\u00e1lisis de datos<\/strong>, sino que tambi\u00e9n ofrece una <strong>interfaz intuitiva y f\u00e1cil de usar<\/strong>. Esto permite a los usuarios acceder a la informaci\u00f3n de manera r\u00e1pida y eficiente, facilitando la toma de decisiones informadas. Adem\u00e1s, la plataforma al ser escalable se adapta a un volumen creciente de datos sin comprometer el rendimiento.<\/p>\r\n<!-- wp:image {\"id\":15923,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} -->\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-15923\" src=\"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Polar-Plot-Mapa-1024x576.png\" alt=\"\" \/><\/figure>\r\n<h2>\u00bfC\u00f3mo est\u00e1n usando nuestros clientes el software?<\/h2>\r\n<h3>Vigilancia de la calidad del aire en minas<\/h3>\r\n<p>La generadora y Comercializadora de Energ\u00eda del Caribe, <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/casos-de-exito\/sistema-de-vigilancia-de-la-calidad-del-aire-en-minas\/\">Gecelca S.A E.S.P<\/a>, requer\u00eda de un sistema de vigilancia de la calidad del aire en la mina de carb\u00f3n Las Palmeras en C\u00f3rdoba, Colombia. Para ello, se despleg\u00f3 una red h\u00edbrida de calidad del aire compuesta por 3 estaciones m\u00f3viles Grimm EDM180 para la medici\u00f3n de PMs y 3 estaciones Kunak AIR Pro para medir gases contaminantes y PMs. El software de Kunak AIR Cloud fue clave en este proyecto ya que permiti\u00f3 la gesti\u00f3n de la informaci\u00f3n recopilada por la red de sensores, y realizando un an\u00e1lisis avanzado de los datos para la toma de decisiones.<\/p>\r\n<h3>Monitorizaci\u00f3n de la calidad del aire y el estr\u00e9s t\u00e9rmico durante la pr\u00e1ctica de deporte<\/h3>\r\n<p>En el Mundial de Atletismo en Budapest 2023, la Asociaci\u00f3n Mundial de Atletismo (World Athletics) se comprometi\u00f3 a <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/casos-de-exito\/monitorizacion-de-la-calidad-del-aire-y-estres-termico-budapest-2023\/\">registrar la calidad del aire durante todos los campeonatos del mundo de atletismo<\/a>. Kunak fue contratada para controlar el estr\u00e9s t\u00e9rmico con el desarrollo de una <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/accesorios\/#termometro-de-globo-y-de-bulbo-humedo-wbgt\">sonda WBGT<\/a> espec\u00edfica junto con los contaminantes atmosf\u00e9ricos. De esta manera los atletas eran informados sobre los contaminantes a los que estaban expuestos. Adem\u00e1s, fue posible acceder a los datos en directo gracias al desarrollo de un <a target=\"_blank\" href=\"https:\/\/worldathletics.org\/athletics-better-world\/air-quality\/air-quality-live\">widget embebido en la web de World Athletics<\/a>.<\/p>\r\n<p><span style=\"font-size: 18pt;\">Conclusi\u00f3n<\/span><\/p>\r\n<p>La mala calidad del aire es un problema que solo se hace perceptible cuando los niveles de contaminaci\u00f3n aumentan. Pero la salud de las personas se puede ver condicionada incluso por exposiciones continuadas a agentes contaminantes dentro de los l\u00edmites legales. Numerosos estudios han demostrado, de hecho, que no hay un nivel seguro de contaminaci\u00f3n.<\/p>\r\n<p>La monitorizaci\u00f3n continua de las variables atmosf\u00e9ricas es, por tanto, una forma de reducir las consecuencias de esta amenaza. Implica confiar en avances como la plataforma web Kunak AIR Cloud, un software dise\u00f1ado para obtener el mayor rendimiento de las estaciones de calidad del aire de Kunak. Esta combinaci\u00f3n de herramientas conforma nuestra soluci\u00f3n vertical de medici\u00f3n de la calidad del aire. Por un lado, <a target=\"_blank\" href=\"https:\/\/kunakair.com\/es\/el-sensor-de-calidad-del-aire-mas-preciso\/\">los galardonados Kunak AIR Pro y Kunak AIR Lite<\/a>. Por el otro, la potente plataforma web Kunak AIR Cloud. Juntos, la mejor opci\u00f3n para adoptar las medidas correctas y garantizar una buena calidad del aire.<\/p>\r\n<p>Porque como aseguran Snyder <em>et al<\/em> (2),<\/p>\r\n<blockquote>\r\n<p>\u00ab<em>los datos de mala o calidad desconocida son menos \u00fatiles que la ausencia de datos, ya que pueden llevar a decisiones equivocadas<\/em>\u00bb.<\/p>\r\n<\/blockquote>\r\n<p>T\u00fa tienes la \u00faltima palabra.<\/p>\r\n<!-- \/wp:image -->\r\n<p><span style=\"font-size: 18pt;\">Fuentes consultadas<\/span><\/p>\r\n<ul>\r\n<li>(1) Arroyo, P., Herrero, J., Su\u00e1rez, J., &amp; Lozano, J. (2019). Wireless Sensor Network Combined with Cloud Computing for Air Quality Monitoring. Sensors, 19(3), 691. <a href=\"https:\/\/doi.org\/10.3390\/s19030691\" target=\"_blank\" rel=\"noopener\">https:\/\/doi.org\/10.3390\/s19030691<\/a><\/li>\r\n<li>(2) Snyder E., Watkins T., Solomon P., Thoma E.,Williams R., Hagler G., Shelow D., Hindin D., Kilaru V., Preuss P. (2013). The Changing Paradigm of Air Pollution Monitoring. Environmental Science &amp; Technology, 47(20), 11369\u201311377. <a href=\"https:\/\/doi.org\/10.1021\/es4022602\" target=\"_blank\" rel=\"noopener\">https:\/\/doi.org\/10.1021\/es4022602<\/a><\/li>\r\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Las virtudes de nuestro Kunak AIR Pro son conocidas, pero \u00bfsabes que la plataforma web Kunak Cloud lo hace a\u00fan m\u00e1s grande?<\/p>\n","protected":false},"author":6,"featured_media":23346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[164],"tags":[411,205],"resources":[379,396],"class_list":["post-15909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","tag-calidad-del-aire","tag-contaminantes-atmosfericos","resources-articulos","resources-productos-kunak"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kunak AIR Cloud, el avanzado software de calidad del aire - Kunak<\/title>\n<meta name=\"description\" content=\"Las virtudes del Kunak AIR Pro son conocidas, pero \u00bfsabes que Kunak AIR Cloud te permite visualizar y analizar los datos recopilados?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kunak AIR Cloud, el avanzado software de calidad del aire - Kunak\" \/>\n<meta property=\"og:description\" content=\"Las virtudes del Kunak AIR Pro son conocidas, pero \u00bfsabes que Kunak AIR Cloud te permite visualizar y analizar los datos recopilados?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KunakTechnologies\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/kunakair\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T08:02:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T10:45:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:site\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kunak AIR Cloud, el avanzado software de calidad del aire - Kunak","description":"Las virtudes del Kunak AIR Pro son conocidas, pero \u00bfsabes que Kunak AIR Cloud te permite visualizar y analizar los datos recopilados?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/","og_locale":"es_ES","og_type":"article","og_title":"Kunak AIR Cloud, el avanzado software de calidad del aire - Kunak","og_description":"Las virtudes del Kunak AIR Pro son conocidas, pero \u00bfsabes que Kunak AIR Cloud te permite visualizar y analizar los datos recopilados?","og_url":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/","og_site_name":"Kunak","article_publisher":"https:\/\/www.facebook.com\/KunakTechnologies\/","article_author":"https:\/\/www.facebook.com\/kunakair","article_published_time":"2022-01-18T08:02:45+00:00","article_modified_time":"2026-06-15T10:45:50+00:00","og_image":[{"width":900,"height":500,"url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg","type":"image\/jpeg"}],"author":"Equipo de marketing y comunicaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@KunaK_sensing","twitter_site":"@KunaK_sensing","twitter_misc":{"Escrito por":"Equipo de marketing y comunicaci\u00f3n","Tiempo de lectura":"14 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#article","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/"},"author":{"name":"Equipo de marketing y comunicaci\u00f3n","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23"},"headline":"Kunak AIR Cloud, software de calidad del aire para el an\u00e1lisis y visualizaci\u00f3n de datos","datePublished":"2022-01-18T08:02:45+00:00","dateModified":"2026-06-15T10:45:50+00:00","mainEntityOfPage":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/"},"wordCount":2987,"commentCount":0,"publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"image":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg","keywords":["Calidad del aire","Contaminantes atmosf\u00e9ricos"],"articleSection":["Art\u00edculos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/","url":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/","name":"Kunak AIR Cloud, el avanzado software de calidad del aire - Kunak","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#primaryimage"},"image":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#primaryimage"},"thumbnailUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg","datePublished":"2022-01-18T08:02:45+00:00","dateModified":"2026-06-15T10:45:50+00:00","description":"Las virtudes del Kunak AIR Pro son conocidas, pero \u00bfsabes que Kunak AIR Cloud te permite visualizar y analizar los datos recopilados?","breadcrumb":{"@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#primaryimage","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/01\/Kunak-Cloud-plataforma-web-calidad-del-aire.jpg","width":900,"height":500,"caption":"Kunak Cloud, la plataforma web de visualizaci\u00f3n y an\u00e1lisis de la calidad del aire"},{"@type":"BreadcrumbList","@id":"https:\/\/kunakair.com\/es\/kunak-cloud-plataforma-web-calidad-aire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kunakair.com\/es\/"},{"@type":"ListItem","position":2,"name":"Kunak AIR Cloud, software de calidad del aire para el an\u00e1lisis y visualizaci\u00f3n de datos"}]},{"@type":"WebSite","@id":"https:\/\/kunakair.com\/es\/#website","url":"https:\/\/kunakair.com\/es\/","name":"KUNAK","description":"Sensing anywhere","publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"alternateName":"Sensing anywhere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunakair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kunakair.com\/es\/#organization","name":"KUNAK","alternateName":"Sensing anywhere","url":"https:\/\/kunakair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","width":1000,"height":1000,"caption":"KUNAK"},"image":{"@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KunakTechnologies\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.youtube.com\/channel\/UC-suigTybwCW50od_rhTZxg"]},{"@type":"Person","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23","name":"Equipo de marketing y comunicaci\u00f3n","sameAs":["https:\/\/www.facebook.com\/kunakair","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.youtube.com\/@kunakair"],"url":"https:\/\/kunakair.com\/es\/author\/kunak\/"}]}},"_links":{"self":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/15909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/comments?post=15909"}],"version-history":[{"count":9,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/15909\/revisions"}],"predecessor-version":[{"id":59716,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/15909\/revisions\/59716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media\/23346"}],"wp:attachment":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media?parent=15909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/categories?post=15909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/tags?post=15909"},{"taxonomy":"resources","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/resources?post=15909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}