{"id":1195,"date":"2017-10-27T11:28:23","date_gmt":"2017-10-27T10:28:23","guid":{"rendered":"https:\/\/kunakes.jaimezubiaur.com\/?p=1195"},"modified":"2026-06-15T13:02:17","modified_gmt":"2026-06-15T11:02:17","slug":"kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna","status":"publish","type":"post","link":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/","title":{"rendered":"Kunak Environment en la Jornada IoT del Instituto Smart Cities de la UPNA"},"content":{"rendered":"<p>Kunak ha participado en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA (Universidad P\u00fablica de Navarra), que ha tenido lugar hoy viernes 27 de octubre en el Palacio del Condestable de Pamplona.<\/p>\n<p>Nuestra firma ha presentando los\u00a0sistemas Kunak Environment para la monitorizaci\u00f3n de la calidad del aire y la contaminaci\u00f3n ac\u00fastica y la plataforma Kunak Air Cloud\u00a0a representantes del Gobierno, Mancomunidad, Ayuntamiento, empresas, etc.<\/p>\n<p>El <a href=\"https:\/\/www.unavarra.es\/isc\/\" target=\"_blank\" rel=\"noopener\">Instituto de Smart Cities\u00a0ISC<\/a>\u00a0es el instituto de la Universidad P\u00fablica de Navarra orientado al\u00a0dise\u00f1o, an\u00e1lisis, implementaci\u00f3n y optimizaci\u00f3n\u00a0de\u00a0entornos inteligentes para ciudades que desde 2014 contribuye a la divulgaci\u00f3n y al desarrollo tecnol\u00f3gico y estrat\u00e9gico del concepto de \u201cSmart Cities\u201d as\u00ed como a su difusi\u00f3n e implementaci\u00f3n pr\u00e1ctica a nivel local, regional, estatal e internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kunak ha participado en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA (Universidad P\u00fablica de Navarra), que ha tenido lugar hoy viernes 27 de octubre en el Palacio del Condestable de Pamplona. Nuestra firma ha presentando los\u00a0sistemas Kunak Environment para la monitorizaci\u00f3n de la calidad del aire y la contaminaci\u00f3n ac\u00fastica y la plataforma Kunak Air Cloud\u00a0a representantes [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[164],"tags":[359],"resources":[],"class_list":["post-1195","post","type-post","status-publish","format-standard","hentry","category-articulos","tag-monitorizacion-ambiental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA | Kunak<\/title>\n<meta name=\"description\" content=\"Kunak en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA, con los\u00a0sistemas para la monitorizaci\u00f3n de la calidad del aire y el ruido urbano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA | Kunak\" \/>\n<meta property=\"og:description\" content=\"Kunak en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA, con los\u00a0sistemas para la monitorizaci\u00f3n de la calidad del aire y el ruido urbano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KunakTechnologies\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/kunakair\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-27T10:28:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T11:02:17+00:00\" \/>\n<meta name=\"author\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:site\" content=\"@KunaK_sensing\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo de marketing y comunicaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA | Kunak","description":"Kunak en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA, con los\u00a0sistemas para la monitorizaci\u00f3n de la calidad del aire y el ruido urbano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/","og_locale":"es_ES","og_type":"article","og_title":"Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA | Kunak","og_description":"Kunak en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA, con los\u00a0sistemas para la monitorizaci\u00f3n de la calidad del aire y el ruido urbano.","og_url":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/","og_site_name":"Kunak","article_publisher":"https:\/\/www.facebook.com\/KunakTechnologies\/","article_author":"https:\/\/www.facebook.com\/kunakair","article_published_time":"2017-10-27T10:28:23+00:00","article_modified_time":"2026-06-15T11:02:17+00:00","author":"Equipo de marketing y comunicaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@KunaK_sensing","twitter_site":"@KunaK_sensing","twitter_misc":{"Escrito por":"Equipo de marketing y comunicaci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/#article","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/"},"author":{"name":"Equipo de marketing y comunicaci\u00f3n","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23"},"headline":"Kunak Environment en la Jornada IoT del Instituto Smart Cities de la UPNA","datePublished":"2017-10-27T10:28:23+00:00","dateModified":"2026-06-15T11:02:17+00:00","mainEntityOfPage":{"@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/"},"wordCount":154,"commentCount":0,"publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"keywords":["Monitorizaci\u00f3n ambiental"],"articleSection":["Art\u00edculos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/","url":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/","name":"Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA | Kunak","isPartOf":{"@id":"https:\/\/kunakair.com\/es\/#website"},"datePublished":"2017-10-27T10:28:23+00:00","dateModified":"2026-06-15T11:02:17+00:00","description":"Kunak en la Jornada\u00a0IoT del Instituto\u00a0Smart\u00a0Cities\u00a0de la\u00a0UPNA, con los\u00a0sistemas para la monitorizaci\u00f3n de la calidad del aire y el ruido urbano.","breadcrumb":{"@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kunakair.com\/es\/kunak-en-la-jornada-iot-del-instituto-smart-cities-de-la-upna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/kunakair.com\/es\/"},{"@type":"ListItem","position":2,"name":"Kunak Environment en la Jornada IoT del Instituto Smart Cities de la UPNA"}]},{"@type":"WebSite","@id":"https:\/\/kunakair.com\/es\/#website","url":"https:\/\/kunakair.com\/es\/","name":"KUNAK","description":"Sensing anywhere","publisher":{"@id":"https:\/\/kunakair.com\/es\/#organization"},"alternateName":"Sensing anywhere","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunakair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kunakair.com\/es\/#organization","name":"KUNAK","alternateName":"Sensing anywhere","url":"https:\/\/kunakair.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","contentUrl":"https:\/\/kunakair.com\/wp-content\/uploads\/2022\/09\/logo-kunak-cuadrado.jpg","width":1000,"height":1000,"caption":"KUNAK"},"image":{"@id":"https:\/\/kunakair.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KunakTechnologies\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.youtube.com\/channel\/UC-suigTybwCW50od_rhTZxg"]},{"@type":"Person","@id":"https:\/\/kunakair.com\/es\/#\/schema\/person\/32d5e976014d392d8b9f27bd02790a23","name":"Equipo de marketing y comunicaci\u00f3n","sameAs":["https:\/\/www.facebook.com\/kunakair","https:\/\/www.instagram.com\/kunak_technologies\/","https:\/\/www.linkedin.com\/company\/kunak\/","https:\/\/x.com\/KunaK_sensing","https:\/\/www.youtube.com\/@kunakair"],"url":"https:\/\/kunakair.com\/es\/author\/kunak\/"}]}},"_links":{"self":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/1195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/comments?post=1195"}],"version-history":[{"count":1,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/1195\/revisions"}],"predecessor-version":[{"id":29586,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/posts\/1195\/revisions\/29586"}],"wp:attachment":[{"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/media?parent=1195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/categories?post=1195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/tags?post=1195"},{"taxonomy":"resources","embeddable":true,"href":"https:\/\/kunakair.com\/es\/wp-json\/wp\/v2\/resources?post=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}